{"id":47,"date":"2026-06-25T15:19:33","date_gmt":"2026-06-25T15:19:33","guid":{"rendered":"https:\/\/sobewelcome.com\/?page_id=47"},"modified":"2026-07-15T17:05:54","modified_gmt":"2026-07-15T17:05:54","slug":"dichiarazione-di-accessibilita","status":"publish","type":"page","link":"https:\/\/arkrea.net\/ar\/dichiarazione-di-accessibilita\/","title":{"rendered":"Dichiarazione di Accessibilit\u00e0"},"content":{"rendered":"<h1>Dichiarazione di Accessibilit\u00e0<\/h1>\n<div>\n<p data-start=\"34\" data-end=\"71\" class=\"PDq2pG_selectionAnchorContainer\"><strong data-start=\"34\" data-end=\"59\">Ultimo aggiornamento:<\/strong> Luglio 2026<span aria-hidden=\"true\" class=\"PDq2pG_selectionAnchor\"><\/span><\/p>\n<h2 data-section-id=\"vqcjbr\" data-start=\"73\" data-end=\"113\">Il nostro impegno per l&#8217;accessibilit\u00e0<\/h2>\n<p data-start=\"115\" data-end=\"354\">ARKREA Srl Unipersonale si impegna a garantire che il sito web <strong data-start=\"178\" data-end=\"200\"><a data-start=\"180\" data-end=\"198\" rel=\"noopener\" target=\"_new\" class=\"decorated-link\" href=\"https:\/\/arkrea.net\/\">https:\/\/arkrea.net<\/a><\/strong> sia accessibile al maggior numero possibile di utenti, indipendentemente dalle capacit\u00e0 personali, dalle tecnologie utilizzate o da eventuali disabilit\u00e0.<\/p>\n<p data-start=\"356\" data-end=\"504\">Crediamo che Internet debba essere uno spazio inclusivo, in grado di offrire un&#8217;esperienza di navigazione semplice, intuitiva e accessibile a tutti.<\/p>\n<p data-start=\"506\" data-end=\"738\">Per questo motivo lavoriamo costantemente per migliorare l&#8217;accessibilit\u00e0 del nostro sito e per conformarci alle <strong data-start=\"618\" data-end=\"669\">Web Content Accessibility Guidelines (WCAG) 2.2<\/strong>, livello <strong data-start=\"679\" data-end=\"685\">AA<\/strong>, pubblicate dal <strong data-start=\"702\" data-end=\"737\">World Wide Web Consortium (W3C)<\/strong>.<\/p>\n<hr data-start=\"740\" data-end=\"743\" \/>\n<h1 data-section-id=\"jna79b\" data-start=\"745\" data-end=\"766\">Stato di conformit\u00e0<\/h1>\n<p data-start=\"768\" data-end=\"943\">Il sito \u00e8 stato progettato adottando le migliori pratiche di accessibilit\u00e0 disponibili e utilizza tecnologie dedicate per migliorare continuamente l&#8217;esperienza di navigazione.<\/p>\n<p data-start=\"945\" data-end=\"999\">L&#8217;obiettivo \u00e8 garantire l&#8217;accessibilit\u00e0 a persone con:<\/p>\n<ul data-start=\"1001\" data-end=\"1142\">\n<li data-section-id=\"5v327v\" data-start=\"1001\" data-end=\"1020\">disabilit\u00e0 visive<\/li>\n<li data-section-id=\"1di8dew\" data-start=\"1021\" data-end=\"1042\">cecit\u00e0 o ipovisione<\/li>\n<li data-section-id=\"14wolwg\" data-start=\"1043\" data-end=\"1064\">limitazioni motorie<\/li>\n<li data-section-id=\"1y7siwf\" data-start=\"1065\" data-end=\"1087\">disabilit\u00e0 cognitive<\/li>\n<li data-section-id=\"1xag4tq\" data-start=\"1088\" data-end=\"1108\">difficolt\u00e0 uditive<\/li>\n<li data-section-id=\"181mgcw\" data-start=\"1109\" data-end=\"1142\">altre esigenze di accessibilit\u00e0<\/li>\n<\/ul>\n<p data-start=\"1144\" data-end=\"1281\">Le verifiche e gli aggiornamenti vengono effettuati periodicamente per mantenere il sito conforme ai pi\u00f9 recenti standard internazionali.<\/p>\n<hr data-start=\"1283\" data-end=\"1286\" \/>\n<h1 data-section-id=\"1rlomna\" data-start=\"1288\" data-end=\"1320\">Tecnologie per l&#8217;accessibilit\u00e0<\/h1>\n<p data-start=\"1322\" data-end=\"1503\">Per migliorare continuamente l&#8217;esperienza dell&#8217;utente, il sito utilizza una piattaforma dedicata all&#8217;accessibilit\u00e0 che consente di personalizzare numerosi aspetti della navigazione.<\/p>\n<p data-start=\"1505\" data-end=\"1712\">Il sistema impiega inoltre tecnologie basate su Intelligenza Artificiale che analizzano costantemente il sito, ottimizzando il codice HTML e migliorando la compatibilit\u00e0 con i principali strumenti assistivi.<\/p>\n<hr data-start=\"1714\" data-end=\"1717\" \/>\n<h1 data-section-id=\"1iavta2\" data-start=\"1719\" data-end=\"1752\">Compatibilit\u00e0 con Screen Reader<\/h1>\n<p data-start=\"1754\" data-end=\"1943\">Il sito implementa gli standard <strong data-start=\"1786\" data-end=\"1834\">ARIA (Accessible Rich Internet Applications)<\/strong> che permettono ai software di lettura dello schermo di interpretare correttamente la struttura delle pagine.<\/p>\n<p data-start=\"1945\" data-end=\"1988\">Tra le principali funzionalit\u00e0 disponibili:<\/p>\n<ul data-start=\"1990\" data-end=\"2270\">\n<li data-section-id=\"13vz8lk\" data-start=\"1990\" data-end=\"2026\">descrizioni corrette dei contenuti<\/li>\n<li data-section-id=\"7gxg9w\" data-start=\"2027\" data-end=\"2072\">etichette accessibili per moduli e pulsanti<\/li>\n<li data-section-id=\"jjhpxb\" data-start=\"2073\" data-end=\"2099\">navigazione semplificata<\/li>\n<li data-section-id=\"qlnmhg\" data-start=\"2100\" data-end=\"2146\">descrizioni automatiche delle immagini (ALT)<\/li>\n<li data-section-id=\"1ckpjsg\" data-start=\"2147\" data-end=\"2203\">riconoscimento del testo presente nelle immagini (OCR)<\/li>\n<li data-section-id=\"1mf9ha6\" data-start=\"2204\" data-end=\"2270\">compatibilit\u00e0 con:\n<ul data-start=\"2228\" data-end=\"2270\">\n<li data-section-id=\"1j3wm6f\" data-start=\"2228\" data-end=\"2234\">JAWS<\/li>\n<li data-section-id=\"1j3zwc5\" data-start=\"2237\" data-end=\"2243\">NVDA<\/li>\n<li data-section-id=\"882pu8\" data-start=\"2246\" data-end=\"2257\">VoiceOver<\/li>\n<li data-section-id=\"ua7ys1\" data-start=\"2260\" data-end=\"2270\">TalkBack<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<hr data-start=\"2272\" data-end=\"2275\" \/>\n<h1 data-section-id=\"u7w5js\" data-start=\"2277\" data-end=\"2307\">Navigazione tramite tastiera<\/h1>\n<p data-start=\"2309\" data-end=\"2456\">Il sito \u00e8 completamente navigabile mediante tastiera, consentendo agli utenti di utilizzare tutte le principali funzionalit\u00e0 senza l&#8217;uso del mouse.<\/p>\n<p data-start=\"2458\" data-end=\"2474\">Sono supportati:<\/p>\n<ul data-start=\"2476\" data-end=\"2703\">\n<li data-section-id=\"4l63w5\" data-start=\"2476\" data-end=\"2513\">navigazione tramite TAB e SHIFT+TAB<\/li>\n<li data-section-id=\"1a9o5zb\" data-start=\"2514\" data-end=\"2533\">apertura dei menu<\/li>\n<li data-section-id=\"10ivfpa\" data-start=\"2534\" data-end=\"2555\">gestione dei moduli<\/li>\n<li data-section-id=\"1rzai6s\" data-start=\"2556\" data-end=\"2594\">selezione di pulsanti e collegamenti<\/li>\n<li data-section-id=\"15kw5bm\" data-start=\"2595\" data-end=\"2627\">gestione delle finestre modali<\/li>\n<li data-section-id=\"61ta26\" data-start=\"2628\" data-end=\"2656\">menu di salto ai contenuti<\/li>\n<li data-section-id=\"15vi2mo\" data-start=\"2657\" data-end=\"2703\">gestione automatica del focus della tastiera<\/li>\n<\/ul>\n<hr data-start=\"2705\" data-end=\"2708\" \/>\n<h1 data-section-id=\"dyzwx8\" data-start=\"2710\" data-end=\"2746\">Personalizzazione dell&#8217;interfaccia<\/h1>\n<p data-start=\"2748\" data-end=\"2860\">Gli utenti possono modificare numerosi aspetti della visualizzazione per adattare il sito alle proprie esigenze.<\/p>\n<p data-start=\"2862\" data-end=\"2900\">Tra le principali opzioni disponibili:<\/p>\n<h3 data-section-id=\"79tltr\" data-start=\"2902\" data-end=\"2911\">Testo<\/h3>\n<ul data-start=\"2913\" data-end=\"3069\">\n<li data-section-id=\"wixiw1\" data-start=\"2913\" data-end=\"2965\">aumento o riduzione della dimensione dei caratteri<\/li>\n<li data-section-id=\"1aznl5g\" data-start=\"2966\" data-end=\"2985\">modifica del font<\/li>\n<li data-section-id=\"1h1g9vk\" data-start=\"2986\" data-end=\"3015\">regolazione dell&#8217;interlinea<\/li>\n<li data-section-id=\"1otiqpi\" data-start=\"3016\" data-end=\"3040\">spaziatura tra lettere<\/li>\n<li data-section-id=\"vtt6au\" data-start=\"3041\" data-end=\"3069\">allineamento dei paragrafi<\/li>\n<\/ul>\n<h3 data-section-id=\"eqkf2q\" data-start=\"3071\" data-end=\"3081\">Colori<\/h3>\n<p data-start=\"3083\" data-end=\"3140\">\u00c8 possibile selezionare differenti modalit\u00e0 di contrasto:<\/p>\n<ul data-start=\"3142\" data-end=\"3210\">\n<li data-section-id=\"1bfl5ti\" data-start=\"3142\" data-end=\"3150\">chiaro<\/li>\n<li data-section-id=\"16ndckw\" data-start=\"3151\" data-end=\"3158\">scuro<\/li>\n<li data-section-id=\"9iqmko\" data-start=\"3159\" data-end=\"3174\">monocromatico<\/li>\n<li data-section-id=\"1tz7qxf\" data-start=\"3175\" data-end=\"3191\">alto contrasto<\/li>\n<li data-section-id=\"1t91su2\" data-start=\"3192\" data-end=\"3210\">colori invertiti<\/li>\n<\/ul>\n<p data-start=\"3212\" data-end=\"3296\">oltre a numerose combinazioni cromatiche dedicate ai diversi tipi di deficit visivi.<\/p>\n<h3 data-section-id=\"nwhq2f\" data-start=\"3298\" data-end=\"3312\">Animazioni<\/h3>\n<p data-start=\"3314\" data-end=\"3368\">Gli utenti sensibili al movimento possono disattivare:<\/p>\n<ul data-start=\"3370\" data-end=\"3445\">\n<li data-section-id=\"f7c0vt\" data-start=\"3370\" data-end=\"3382\">animazioni<\/li>\n<li data-section-id=\"f9t8xn\" data-start=\"3383\" data-end=\"3396\">GIF animate<\/li>\n<li data-section-id=\"1t5jaci\" data-start=\"3397\" data-end=\"3410\">effetti CSS<\/li>\n<li data-section-id=\"7a0n8y\" data-start=\"3411\" data-end=\"3445\">video in riproduzione automatica<\/li>\n<\/ul>\n<h3 data-section-id=\"1gd5ccr\" data-start=\"3447\" data-end=\"3479\">Evidenziazione dei contenuti<\/h3>\n<p data-start=\"3481\" data-end=\"3505\">\u00c8 possibile evidenziare:<\/p>\n<ul data-start=\"3507\" data-end=\"3587\">\n<li data-section-id=\"1waupks\" data-start=\"3507\" data-end=\"3521\">collegamenti<\/li>\n<li data-section-id=\"1l56nu3\" data-start=\"3522\" data-end=\"3530\">titoli<\/li>\n<li data-section-id=\"11f8ywe\" data-start=\"3531\" data-end=\"3553\">elementi selezionati<\/li>\n<li data-section-id=\"qsa2w\" data-start=\"3554\" data-end=\"3587\">elementi al passaggio del mouse<\/li>\n<\/ul>\n<h3 data-section-id=\"70wuog\" data-start=\"3589\" data-end=\"3598\">Audio<\/h3>\n<p data-start=\"3600\" data-end=\"3676\">L&#8217;audio automatico pu\u00f2 essere disattivato completamente con un solo comando.<\/p>\n<h3 data-section-id=\"1h81ir2\" data-start=\"3678\" data-end=\"3700\">Supporto Cognitivo<\/h3>\n<p data-start=\"3702\" data-end=\"3865\">Il sistema integra strumenti di supporto che aiutano gli utenti a comprendere termini complessi, abbreviazioni e definizioni attraverso fonti informative dedicate.<\/p>\n<h3 data-section-id=\"1l76hb1\" data-start=\"3867\" data-end=\"3890\">Funzioni aggiuntive<\/h3>\n<p data-start=\"3892\" data-end=\"3917\">Sono inoltre disponibili:<\/p>\n<ul data-start=\"3919\" data-end=\"4079\">\n<li data-section-id=\"11emzat\" data-start=\"3919\" data-end=\"3945\">cursore personalizzabile<\/li>\n<li data-section-id=\"3wrww1\" data-start=\"3946\" data-end=\"3965\">tastiera virtuale<\/li>\n<li data-section-id=\"1msuo84\" data-start=\"3966\" data-end=\"3983\">modalit\u00e0 stampa<\/li>\n<li data-section-id=\"uekwbe\" data-start=\"3984\" data-end=\"4026\">regolazione della dimensione del cursore<\/li>\n<li data-section-id=\"hvhqw7\" data-start=\"4027\" data-end=\"4079\">ulteriori strumenti di assistenza alla navigazione<\/li>\n<\/ul>\n<hr data-start=\"4081\" data-end=\"4084\" \/>\n<h1 data-section-id=\"ff47ro\" data-start=\"4086\" data-end=\"4136\">Compatibilit\u00e0 con browser e tecnologie assistive<\/h1>\n<p data-start=\"4138\" data-end=\"4269\">Il sito \u00e8 stato sviluppato per garantire la massima compatibilit\u00e0 con i principali browser e dispositivi oggi disponibili, tra cui:<\/p>\n<ul data-start=\"4271\" data-end=\"4344\">\n<li data-section-id=\"14v3qin\" data-start=\"4271\" data-end=\"4286\">Google Chrome<\/li>\n<li data-section-id=\"8t5f5d\" data-start=\"4287\" data-end=\"4304\">Mozilla Firefox<\/li>\n<li data-section-id=\"1rgnd6n\" data-start=\"4305\" data-end=\"4321\">Microsoft Edge<\/li>\n<li data-section-id=\"5pvfda\" data-start=\"4322\" data-end=\"4336\">Apple Safari<\/li>\n<li data-section-id=\"16uyuqp\" data-start=\"4337\" data-end=\"4344\">Opera<\/li>\n<\/ul>\n<p data-start=\"4346\" data-end=\"4458\">Il sito supporta inoltre le principali tecnologie assistive utilizzate su sistemi Windows, macOS, Android e iOS.<\/p>\n<hr data-start=\"4460\" data-end=\"4463\" \/>\n<h1 data-section-id=\"1uuvya2\" data-start=\"4465\" data-end=\"4489\">Miglioramento continuo<\/h1>\n<p data-start=\"4491\" data-end=\"4540\">L&#8217;accessibilit\u00e0 rappresenta un processo continuo.<\/p>\n<p data-start=\"4542\" data-end=\"4730\">ARKREA Srl Unipersonale monitora costantemente il sito per individuare eventuali criticit\u00e0 e introdurre nuove soluzioni tecnologiche che migliorino ulteriormente l&#8217;esperienza degli utenti.<\/p>\n<p data-start=\"4732\" data-end=\"4973\">Nonostante il nostro costante impegno, alcune pagine o funzionalit\u00e0 potrebbero essere temporaneamente in fase di aggiornamento o miglioramento. Continueremo a lavorare affinch\u00e9 il sito raggiunga il massimo livello di accessibilit\u00e0 possibile.<\/p>\n<hr data-start=\"4975\" data-end=\"4978\" \/>\n<h1 data-section-id=\"1pqmc8\" data-start=\"4980\" data-end=\"4990\">Contatti<\/h1>\n<p data-start=\"4992\" data-end=\"5162\">Qualora riscontrassi difficolt\u00e0 nella consultazione del sito o desiderassi inviare suggerimenti per migliorarne l&#8217;accessibilit\u00e0, saremo lieti di ricevere il tuo feedback.<\/p>\n<p data-start=\"5164\" data-end=\"5235\"><strong data-start=\"5164\" data-end=\"5191\">ARKREA Srl Unipersonale<\/strong><br data-start=\"5191\" data-end=\"5194\" \/>Via Fermo, 32<br data-start=\"5207\" data-end=\"5210\" \/>61122 Pesaro (PU), Italia<\/p>\n<p data-start=\"5237\" data-end=\"5299\"><strong data-start=\"5237\" data-end=\"5250\">Telefono:<\/strong> +39 0721 47 24 83<br data-start=\"5268\" data-end=\"5271\" \/><strong data-start=\"5271\" data-end=\"5281\">Email:<\/strong> <a data-start=\"5282\" data-end=\"5299\" class=\"decorated-link cursor-pointer\" rel=\"noopener\">ordini@arkrea.net<\/a><\/p>\n<p data-start=\"5301\" data-end=\"5333\"><strong data-start=\"5301\" data-end=\"5314\">Sito web:<\/strong> <a data-start=\"5315\" data-end=\"5333\" rel=\"noopener\" target=\"_new\" class=\"decorated-link\" href=\"https:\/\/arkrea.net\/\">https:\/\/arkrea.net<\/a><\/p>\n<p data-start=\"5335\" data-end=\"5412\">Per contattarci direttamente puoi utilizzare il modulo presente nella pagina:<\/p>\n<p data-start=\"5414\" data-end=\"5445\"><strong data-start=\"5414\" data-end=\"5445\"><a data-start=\"5416\" data-end=\"5443\" rel=\"noopener\" target=\"_new\" class=\"decorated-link\" href=\"https:\/\/arkrea.net\/contatti\">https:\/\/arkrea.net\/contatti<\/a><\/strong><\/p>\n<\/div>\n<p><!--more--><br \/>\n<!-- {\"type\":\"layout\",\"children\":[{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"middle\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"Dichiarazione di Accessibilit\u00e0\",\"image_align\":\"left\",\"image_margin\":\"xsmall\",\"title_element\":\"h1\"}},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p data-start=\\\"34\\\" data-end=\\\"71\\\" class=\\\"PDq2pG_selectionAnchorContainer\\\"><strong data-start=\\\"34\\\" data-end=\\\"59\\\">Ultimo aggiornamento:<\/strong> Luglio 2026<span aria-hidden=\\\"true\\\" class=\\\"PDq2pG_selectionAnchor\\\"><\/span><\/p>\n\n\\n\n\n<h2 data-section-id=\\\"vqcjbr\\\" data-start=\\\"73\\\" data-end=\\\"113\\\">Il nostro impegno per l'accessibilit\u00e0<\/h2>\n\n\\n\n\n<p data-start=\\\"115\\\" data-end=\\\"354\\\">ARKREA Srl Unipersonale si impegna a garantire che il sito web <strong data-start=\\\"178\\\" data-end=\\\"200\\\"><a data-start=\\\"180\\\" data-end=\\\"198\\\" rel=\\\"noopener\\\" target=\\\"_new\\\" class=\\\"decorated-link\\\" href=\\\"https:\/\/arkrea.net\/\\\">https:\/\/arkrea.net<\/a><\/strong> sia accessibile al maggior numero possibile di utenti, indipendentemente dalle capacit\u00e0 personali, dalle tecnologie utilizzate o da eventuali disabilit\u00e0.<\/p>\n\n\\n\n\n<p data-start=\\\"356\\\" data-end=\\\"504\\\">Crediamo che Internet debba essere uno spazio inclusivo, in grado di offrire un'esperienza di navigazione semplice, intuitiva e accessibile a tutti.<\/p>\n\n\\n\n\n<p data-start=\\\"506\\\" data-end=\\\"738\\\">Per questo motivo lavoriamo costantemente per migliorare l'accessibilit\u00e0 del nostro sito e per conformarci alle <strong data-start=\\\"618\\\" data-end=\\\"669\\\">Web Content Accessibility Guidelines (WCAG) 2.2<\/strong>, livello <strong data-start=\\\"679\\\" data-end=\\\"685\\\">AA<\/strong>, pubblicate dal <strong data-start=\\\"702\\\" data-end=\\\"737\\\">World Wide Web Consortium (W3C)<\/strong>.<\/p>\n\n\\n\n\n<hr data-start=\\\"740\\\" data-end=\\\"743\\\" \/>\\n\n\n<h1 data-section-id=\\\"jna79b\\\" data-start=\\\"745\\\" data-end=\\\"766\\\">Stato di conformit\u00e0<\/h1>\n\n\\n\n\n<p data-start=\\\"768\\\" data-end=\\\"943\\\">Il sito \u00e8 stato progettato adottando le migliori pratiche di accessibilit\u00e0 disponibili e utilizza tecnologie dedicate per migliorare continuamente l'esperienza di navigazione.<\/p>\n\n\\n\n\n<p data-start=\\\"945\\\" data-end=\\\"999\\\">L'obiettivo \u00e8 garantire l'accessibilit\u00e0 a persone con:<\/p>\n\n\\n\n\n<ul data-start=\\\"1001\\\" data-end=\\\"1142\\\">\\n\n\n<li data-section-id=\\\"5v327v\\\" data-start=\\\"1001\\\" data-end=\\\"1020\\\">disabilit\u00e0 visive<\/li>\n\n\\n\n\n<li data-section-id=\\\"1di8dew\\\" data-start=\\\"1021\\\" data-end=\\\"1042\\\">cecit\u00e0 o ipovisione<\/li>\n\n\\n\n\n<li data-section-id=\\\"14wolwg\\\" data-start=\\\"1043\\\" data-end=\\\"1064\\\">limitazioni motorie<\/li>\n\n\\n\n\n<li data-section-id=\\\"1y7siwf\\\" data-start=\\\"1065\\\" data-end=\\\"1087\\\">disabilit\u00e0 cognitive<\/li>\n\n\\n\n\n<li data-section-id=\\\"1xag4tq\\\" data-start=\\\"1088\\\" data-end=\\\"1108\\\">difficolt\u00e0 uditive<\/li>\n\n\\n\n\n<li data-section-id=\\\"181mgcw\\\" data-start=\\\"1109\\\" data-end=\\\"1142\\\">altre esigenze di accessibilit\u00e0<\/li>\n\n\\n<\/ul>\n\n\\n\n\n<p data-start=\\\"1144\\\" data-end=\\\"1281\\\">Le verifiche e gli aggiornamenti vengono effettuati periodicamente per mantenere il sito conforme ai pi\u00f9 recenti standard internazionali.<\/p>\n\n\\n\n\n<hr data-start=\\\"1283\\\" data-end=\\\"1286\\\" \/>\\n\n\n<h1 data-section-id=\\\"1rlomna\\\" data-start=\\\"1288\\\" data-end=\\\"1320\\\">Tecnologie per l'accessibilit\u00e0<\/h1>\n\n\\n\n\n<p data-start=\\\"1322\\\" data-end=\\\"1503\\\">Per migliorare continuamente l'esperienza dell'utente, il sito utilizza una piattaforma dedicata all'accessibilit\u00e0 che consente di personalizzare numerosi aspetti della navigazione.<\/p>\n\n\\n\n\n<p data-start=\\\"1505\\\" data-end=\\\"1712\\\">Il sistema impiega inoltre tecnologie basate su Intelligenza Artificiale che analizzano costantemente il sito, ottimizzando il codice HTML e migliorando la compatibilit\u00e0 con i principali strumenti assistivi.<\/p>\n\n\\n\n\n<hr data-start=\\\"1714\\\" data-end=\\\"1717\\\" \/>\\n\n\n<h1 data-section-id=\\\"1iavta2\\\" data-start=\\\"1719\\\" data-end=\\\"1752\\\">Compatibilit\u00e0 con Screen Reader<\/h1>\n\n\\n\n\n<p data-start=\\\"1754\\\" data-end=\\\"1943\\\">Il sito implementa gli standard <strong data-start=\\\"1786\\\" data-end=\\\"1834\\\">ARIA (Accessible Rich Internet Applications)<\/strong> che permettono ai software di lettura dello schermo di interpretare correttamente la struttura delle pagine.<\/p>\n\n\\n\n\n<p data-start=\\\"1945\\\" data-end=\\\"1988\\\">Tra le principali funzionalit\u00e0 disponibili:<\/p>\n\n\\n\n\n<ul data-start=\\\"1990\\\" data-end=\\\"2270\\\">\\n\n\n<li data-section-id=\\\"13vz8lk\\\" data-start=\\\"1990\\\" data-end=\\\"2026\\\">descrizioni corrette dei contenuti<\/li>\n\n\\n\n\n<li data-section-id=\\\"7gxg9w\\\" data-start=\\\"2027\\\" data-end=\\\"2072\\\">etichette accessibili per moduli e pulsanti<\/li>\n\n\\n\n\n<li data-section-id=\\\"jjhpxb\\\" data-start=\\\"2073\\\" data-end=\\\"2099\\\">navigazione semplificata<\/li>\n\n\\n\n\n<li data-section-id=\\\"qlnmhg\\\" data-start=\\\"2100\\\" data-end=\\\"2146\\\">descrizioni automatiche delle immagini (ALT)<\/li>\n\n\\n\n\n<li data-section-id=\\\"1ckpjsg\\\" data-start=\\\"2147\\\" data-end=\\\"2203\\\">riconoscimento del testo presente nelle immagini (OCR)<\/li>\n\n\\n\n\n<li data-section-id=\\\"1mf9ha6\\\" data-start=\\\"2204\\\" data-end=\\\"2270\\\">compatibilit\u00e0 con:\\n\n\n<ul data-start=\\\"2228\\\" data-end=\\\"2270\\\">\\n\n\n<li data-section-id=\\\"1j3wm6f\\\" data-start=\\\"2228\\\" data-end=\\\"2234\\\">JAWS<\/li>\n\n\\n\n\n<li data-section-id=\\\"1j3zwc5\\\" data-start=\\\"2237\\\" data-end=\\\"2243\\\">NVDA<\/li>\n\n\\n\n\n<li data-section-id=\\\"882pu8\\\" data-start=\\\"2246\\\" data-end=\\\"2257\\\">VoiceOver<\/li>\n\n\\n\n\n<li data-section-id=\\\"ua7ys1\\\" data-start=\\\"2260\\\" data-end=\\\"2270\\\">TalkBack<\/li>\n\n\\n<\/ul>\n\n\\n<\/li>\n\n\\n<\/ul>\n\n\\n\n\n<hr data-start=\\\"2272\\\" data-end=\\\"2275\\\" \/>\\n\n\n<h1 data-section-id=\\\"u7w5js\\\" data-start=\\\"2277\\\" data-end=\\\"2307\\\">Navigazione tramite tastiera<\/h1>\n\n\\n\n\n<p data-start=\\\"2309\\\" data-end=\\\"2456\\\">Il sito \u00e8 completamente navigabile mediante tastiera, consentendo agli utenti di utilizzare tutte le principali funzionalit\u00e0 senza l'uso del mouse.<\/p>\n\n\\n\n\n<p data-start=\\\"2458\\\" data-end=\\\"2474\\\">Sono supportati:<\/p>\n\n\\n\n\n<ul data-start=\\\"2476\\\" data-end=\\\"2703\\\">\\n\n\n<li data-section-id=\\\"4l63w5\\\" data-start=\\\"2476\\\" data-end=\\\"2513\\\">navigazione tramite TAB e SHIFT+TAB<\/li>\n\n\\n\n\n<li data-section-id=\\\"1a9o5zb\\\" data-start=\\\"2514\\\" data-end=\\\"2533\\\">apertura dei menu<\/li>\n\n\\n\n\n<li data-section-id=\\\"10ivfpa\\\" data-start=\\\"2534\\\" data-end=\\\"2555\\\">gestione dei moduli<\/li>\n\n\\n\n\n<li data-section-id=\\\"1rzai6s\\\" data-start=\\\"2556\\\" data-end=\\\"2594\\\">selezione di pulsanti e collegamenti<\/li>\n\n\\n\n\n<li data-section-id=\\\"15kw5bm\\\" data-start=\\\"2595\\\" data-end=\\\"2627\\\">gestione delle finestre modali<\/li>\n\n\\n\n\n<li data-section-id=\\\"61ta26\\\" data-start=\\\"2628\\\" data-end=\\\"2656\\\">menu di salto ai contenuti<\/li>\n\n\\n\n\n<li data-section-id=\\\"15vi2mo\\\" data-start=\\\"2657\\\" data-end=\\\"2703\\\">gestione automatica del focus della tastiera<\/li>\n\n\\n<\/ul>\n\n\\n\n\n<hr data-start=\\\"2705\\\" data-end=\\\"2708\\\" \/>\\n\n\n<h1 data-section-id=\\\"dyzwx8\\\" data-start=\\\"2710\\\" data-end=\\\"2746\\\">Personalizzazione dell'interfaccia<\/h1>\n\n\\n\n\n<p data-start=\\\"2748\\\" data-end=\\\"2860\\\">Gli utenti possono modificare numerosi aspetti della visualizzazione per adattare il sito alle proprie esigenze.<\/p>\n\n\\n\n\n<p data-start=\\\"2862\\\" data-end=\\\"2900\\\">Tra le principali opzioni disponibili:<\/p>\n\n\\n\n\n<h3 data-section-id=\\\"79tltr\\\" data-start=\\\"2902\\\" data-end=\\\"2911\\\">Testo<\/h3>\n\n\\n\n\n<ul data-start=\\\"2913\\\" data-end=\\\"3069\\\">\\n\n\n<li data-section-id=\\\"wixiw1\\\" data-start=\\\"2913\\\" data-end=\\\"2965\\\">aumento o riduzione della dimensione dei caratteri<\/li>\n\n\\n\n\n<li data-section-id=\\\"1aznl5g\\\" data-start=\\\"2966\\\" data-end=\\\"2985\\\">modifica del font<\/li>\n\n\\n\n\n<li data-section-id=\\\"1h1g9vk\\\" data-start=\\\"2986\\\" data-end=\\\"3015\\\">regolazione dell'interlinea<\/li>\n\n\\n\n\n<li data-section-id=\\\"1otiqpi\\\" data-start=\\\"3016\\\" data-end=\\\"3040\\\">spaziatura tra lettere<\/li>\n\n\\n\n\n<li data-section-id=\\\"vtt6au\\\" data-start=\\\"3041\\\" data-end=\\\"3069\\\">allineamento dei paragrafi<\/li>\n\n\\n<\/ul>\n\n\\n\n\n<h3 data-section-id=\\\"eqkf2q\\\" data-start=\\\"3071\\\" data-end=\\\"3081\\\">Colori<\/h3>\n\n\\n\n\n<p data-start=\\\"3083\\\" data-end=\\\"3140\\\">\u00c8 possibile selezionare differenti modalit\u00e0 di contrasto:<\/p>\n\n\\n\n\n<ul data-start=\\\"3142\\\" data-end=\\\"3210\\\">\\n\n\n<li data-section-id=\\\"1bfl5ti\\\" data-start=\\\"3142\\\" data-end=\\\"3150\\\">chiaro<\/li>\n\n\\n\n\n<li data-section-id=\\\"16ndckw\\\" data-start=\\\"3151\\\" data-end=\\\"3158\\\">scuro<\/li>\n\n\\n\n\n<li data-section-id=\\\"9iqmko\\\" data-start=\\\"3159\\\" data-end=\\\"3174\\\">monocromatico<\/li>\n\n\\n\n\n<li data-section-id=\\\"1tz7qxf\\\" data-start=\\\"3175\\\" data-end=\\\"3191\\\">alto contrasto<\/li>\n\n\\n\n\n<li data-section-id=\\\"1t91su2\\\" data-start=\\\"3192\\\" data-end=\\\"3210\\\">colori invertiti<\/li>\n\n\\n<\/ul>\n\n\\n\n\n<p data-start=\\\"3212\\\" data-end=\\\"3296\\\">oltre a numerose combinazioni cromatiche dedicate ai diversi tipi di deficit visivi.<\/p>\n\n\\n\n\n<h3 data-section-id=\\\"nwhq2f\\\" data-start=\\\"3298\\\" data-end=\\\"3312\\\">Animazioni<\/h3>\n\n\\n\n\n<p data-start=\\\"3314\\\" data-end=\\\"3368\\\">Gli utenti sensibili al movimento possono disattivare:<\/p>\n\n\\n\n\n<ul data-start=\\\"3370\\\" data-end=\\\"3445\\\">\\n\n\n<li data-section-id=\\\"f7c0vt\\\" data-start=\\\"3370\\\" data-end=\\\"3382\\\">animazioni<\/li>\n\n\\n\n\n<li data-section-id=\\\"f9t8xn\\\" data-start=\\\"3383\\\" data-end=\\\"3396\\\">GIF animate<\/li>\n\n\\n\n\n<li data-section-id=\\\"1t5jaci\\\" data-start=\\\"3397\\\" data-end=\\\"3410\\\">effetti CSS<\/li>\n\n\\n\n\n<li data-section-id=\\\"7a0n8y\\\" data-start=\\\"3411\\\" data-end=\\\"3445\\\">video in riproduzione automatica<\/li>\n\n\\n<\/ul>\n\n\\n\n\n<h3 data-section-id=\\\"1gd5ccr\\\" data-start=\\\"3447\\\" data-end=\\\"3479\\\">Evidenziazione dei contenuti<\/h3>\n\n\\n\n\n<p data-start=\\\"3481\\\" data-end=\\\"3505\\\">\u00c8 possibile evidenziare:<\/p>\n\n\\n\n\n<ul data-start=\\\"3507\\\" data-end=\\\"3587\\\">\\n\n\n<li data-section-id=\\\"1waupks\\\" data-start=\\\"3507\\\" data-end=\\\"3521\\\">collegamenti<\/li>\n\n\\n\n\n<li data-section-id=\\\"1l56nu3\\\" data-start=\\\"3522\\\" data-end=\\\"3530\\\">titoli<\/li>\n\n\\n\n\n<li data-section-id=\\\"11f8ywe\\\" data-start=\\\"3531\\\" data-end=\\\"3553\\\">elementi selezionati<\/li>\n\n\\n\n\n<li data-section-id=\\\"qsa2w\\\" data-start=\\\"3554\\\" data-end=\\\"3587\\\">elementi al passaggio del mouse<\/li>\n\n\\n<\/ul>\n\n\\n\n\n<h3 data-section-id=\\\"70wuog\\\" data-start=\\\"3589\\\" data-end=\\\"3598\\\">Audio<\/h3>\n\n\\n\n\n<p data-start=\\\"3600\\\" data-end=\\\"3676\\\">L'audio automatico pu\u00f2 essere disattivato completamente con un solo comando.<\/p>\n\n\\n\n\n<h3 data-section-id=\\\"1h81ir2\\\" data-start=\\\"3678\\\" data-end=\\\"3700\\\">Supporto Cognitivo<\/h3>\n\n\\n\n\n<p data-start=\\\"3702\\\" data-end=\\\"3865\\\">Il sistema integra strumenti di supporto che aiutano gli utenti a comprendere termini complessi, abbreviazioni e definizioni attraverso fonti informative dedicate.<\/p>\n\n\\n\n\n<h3 data-section-id=\\\"1l76hb1\\\" data-start=\\\"3867\\\" data-end=\\\"3890\\\">Funzioni aggiuntive<\/h3>\n\n\\n\n\n<p data-start=\\\"3892\\\" data-end=\\\"3917\\\">Sono inoltre disponibili:<\/p>\n\n\\n\n\n<ul data-start=\\\"3919\\\" data-end=\\\"4079\\\">\\n\n\n<li data-section-id=\\\"11emzat\\\" data-start=\\\"3919\\\" data-end=\\\"3945\\\">cursore personalizzabile<\/li>\n\n\\n\n\n<li data-section-id=\\\"3wrww1\\\" data-start=\\\"3946\\\" data-end=\\\"3965\\\">tastiera virtuale<\/li>\n\n\\n\n\n<li data-section-id=\\\"1msuo84\\\" data-start=\\\"3966\\\" data-end=\\\"3983\\\">modalit\u00e0 stampa<\/li>\n\n\\n\n\n<li data-section-id=\\\"uekwbe\\\" data-start=\\\"3984\\\" data-end=\\\"4026\\\">regolazione della dimensione del cursore<\/li>\n\n\\n\n\n<li data-section-id=\\\"hvhqw7\\\" data-start=\\\"4027\\\" data-end=\\\"4079\\\">ulteriori strumenti di assistenza alla navigazione<\/li>\n\n\\n<\/ul>\n\n\\n\n\n<hr data-start=\\\"4081\\\" data-end=\\\"4084\\\" \/>\\n\n\n<h1 data-section-id=\\\"ff47ro\\\" data-start=\\\"4086\\\" data-end=\\\"4136\\\">Compatibilit\u00e0 con browser e tecnologie assistive<\/h1>\n\n\\n\n\n<p data-start=\\\"4138\\\" data-end=\\\"4269\\\">Il sito \u00e8 stato sviluppato per garantire la massima compatibilit\u00e0 con i principali browser e dispositivi oggi disponibili, tra cui:<\/p>\n\n\\n\n\n<ul data-start=\\\"4271\\\" data-end=\\\"4344\\\">\\n\n\n<li data-section-id=\\\"14v3qin\\\" data-start=\\\"4271\\\" data-end=\\\"4286\\\">Google Chrome<\/li>\n\n\\n\n\n<li data-section-id=\\\"8t5f5d\\\" data-start=\\\"4287\\\" data-end=\\\"4304\\\">Mozilla Firefox<\/li>\n\n\\n\n\n<li data-section-id=\\\"1rgnd6n\\\" data-start=\\\"4305\\\" data-end=\\\"4321\\\">Microsoft Edge<\/li>\n\n\\n\n\n<li data-section-id=\\\"5pvfda\\\" data-start=\\\"4322\\\" data-end=\\\"4336\\\">Apple Safari<\/li>\n\n\\n\n\n<li data-section-id=\\\"16uyuqp\\\" data-start=\\\"4337\\\" data-end=\\\"4344\\\">Opera<\/li>\n\n\\n<\/ul>\n\n\\n\n\n<p data-start=\\\"4346\\\" data-end=\\\"4458\\\">Il sito supporta inoltre le principali tecnologie assistive utilizzate su sistemi Windows, macOS, Android e iOS.<\/p>\n\n\\n\n\n<hr data-start=\\\"4460\\\" data-end=\\\"4463\\\" \/>\\n\n\n<h1 data-section-id=\\\"1uuvya2\\\" data-start=\\\"4465\\\" data-end=\\\"4489\\\">Miglioramento continuo<\/h1>\n\n\\n\n\n<p data-start=\\\"4491\\\" data-end=\\\"4540\\\">L'accessibilit\u00e0 rappresenta un processo continuo.<\/p>\n\n\\n\n\n<p data-start=\\\"4542\\\" data-end=\\\"4730\\\">ARKREA Srl Unipersonale monitora costantemente il sito per individuare eventuali criticit\u00e0 e introdurre nuove soluzioni tecnologiche che migliorino ulteriormente l'esperienza degli utenti.<\/p>\n\n\\n\n\n<p data-start=\\\"4732\\\" data-end=\\\"4973\\\">Nonostante il nostro costante impegno, alcune pagine o funzionalit\u00e0 potrebbero essere temporaneamente in fase di aggiornamento o miglioramento. Continueremo a lavorare affinch\u00e9 il sito raggiunga il massimo livello di accessibilit\u00e0 possibile.<\/p>\n\n\\n\n\n<hr data-start=\\\"4975\\\" data-end=\\\"4978\\\" \/>\\n\n\n<h1 data-section-id=\\\"1pqmc8\\\" data-start=\\\"4980\\\" data-end=\\\"4990\\\">Contatti<\/h1>\n\n\\n\n\n<p data-start=\\\"4992\\\" data-end=\\\"5162\\\">Qualora riscontrassi difficolt\u00e0 nella consultazione del sito o desiderassi inviare suggerimenti per migliorarne l'accessibilit\u00e0, saremo lieti di ricevere il tuo feedback.<\/p>\n\n\\n\n\n<p data-start=\\\"5164\\\" data-end=\\\"5235\\\"><strong data-start=\\\"5164\\\" data-end=\\\"5191\\\">ARKREA Srl Unipersonale<\/strong><br data-start=\\\"5191\\\" data-end=\\\"5194\\\" \/>Via Fermo, 32<br data-start=\\\"5207\\\" data-end=\\\"5210\\\" \/>61122 Pesaro (PU), Italia<\/p>\n\n\\n\n\n<p data-start=\\\"5237\\\" data-end=\\\"5299\\\"><strong data-start=\\\"5237\\\" data-end=\\\"5250\\\">Telefono:<\/strong> +39 0721 47 24 83<br data-start=\\\"5268\\\" data-end=\\\"5271\\\" \/><strong data-start=\\\"5271\\\" data-end=\\\"5281\\\">Email:<\/strong> <a data-start=\\\"5282\\\" data-end=\\\"5299\\\" class=\\\"decorated-link cursor-pointer\\\" rel=\\\"noopener\\\">ordini@arkrea.net<\/a><\/p>\n\n\\n\n\n<p data-start=\\\"5301\\\" data-end=\\\"5333\\\"><strong data-start=\\\"5301\\\" data-end=\\\"5314\\\">Sito web:<\/strong> <a data-start=\\\"5315\\\" data-end=\\\"5333\\\" rel=\\\"noopener\\\" target=\\\"_new\\\" class=\\\"decorated-link\\\" href=\\\"https:\/\/arkrea.net\/\\\">https:\/\/arkrea.net<\/a><\/p>\n\n\\n\n\n<p data-start=\\\"5335\\\" data-end=\\\"5412\\\">Per contattarci direttamente puoi utilizzare il modulo presente nella pagina:<\/p>\n\n\\n\n\n<p data-start=\\\"5414\\\" data-end=\\\"5445\\\"><strong data-start=\\\"5414\\\" data-end=\\\"5445\\\"><a data-start=\\\"5416\\\" data-end=\\\"5443\\\" rel=\\\"noopener\\\" target=\\\"_new\\\" class=\\\"decorated-link\\\" href=\\\"https:\/\/arkrea.net\/contatti\\\">https:\/\/arkrea.net\/contatti<\/a><\/strong><\/p>\n\n\",\"margin_bottom\":\"default\",\"margin_top\":\"default\"}}]}]}]}],\"version\":\"5.0.36\"} --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dichiarazione di Accessibilit\u00e0 Ultimo aggiornamento: Luglio 2026 Il nostro impegno per l&#8217;accessibilit\u00e0 ARKREA Srl Unipersonale si impegna a garantire che il sito web https:\/\/arkrea.net sia accessibile al maggior numero possibile di utenti, indipendentemente dalle capacit\u00e0 personali, dalle tecnologie utilizzate o da eventuali disabilit\u00e0. Crediamo che Internet debba essere uno spazio inclusivo, in grado di offrire [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-47","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/arkrea.net\/ar\/wp-json\/wp\/v2\/pages\/47","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arkrea.net\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/arkrea.net\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/arkrea.net\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/arkrea.net\/ar\/wp-json\/wp\/v2\/comments?post=47"}],"version-history":[{"count":4,"href":"https:\/\/arkrea.net\/ar\/wp-json\/wp\/v2\/pages\/47\/revisions"}],"predecessor-version":[{"id":562,"href":"https:\/\/arkrea.net\/ar\/wp-json\/wp\/v2\/pages\/47\/revisions\/562"}],"wp:attachment":[{"href":"https:\/\/arkrea.net\/ar\/wp-json\/wp\/v2\/media?parent=47"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}