{"id":385,"date":"2026-06-30T17:51:03","date_gmt":"2026-06-30T17:51:03","guid":{"rendered":"https:\/\/sobewelcome.com\/?page_id=385"},"modified":"2026-06-30T22:30:47","modified_gmt":"2026-06-30T22:30:47","slug":"rivestimenti-ceramin","status":"publish","type":"page","link":"https:\/\/arkrea.net\/fr\/rivestimenti-ceramin\/","title":{"rendered":"Rev\u00eatements CERAMIN"},"content":{"rendered":"<h1>CERAMIN<\/h1>\n<div>\n<p>Rivestimenti da parete CERAMIN: Innovazione Sostenibile per gli Interni di Domani<\/p>\n<\/div>\n<div>\n<p>La collezione <strong>CERAMIN<\/strong> by Arkrea rappresenta una nuova generazione di rivestimenti da parete progettati per chi desidera coniugare design, prestazioni e rispetto per l\u2019ambiente. Grazie a un innovativo materiale minerale privo di PVC, <strong>CERAMIN<\/strong> offre una soluzione moderna e sostenibile che unisce l\u2019estetica delle superfici naturali alla praticit\u00e0 delle pi\u00f9 avanzate tecnologie per rivestimenti.<\/p>\n<p>Ideali per abitazioni, uffici, negozi e spazi commerciali, i rivestimenti\u00a0<strong>CERAMIN<\/strong> garantiscono un perfetto equilibrio tra eleganza, durata e benessere abitativo.<\/p>\n<\/div>\n<h1>RINNOVA IL TUO BAGNO CON FACILITA&#8217;<\/h1>\n<div>Vuoi ridare nuova vita ai bagni della tua casa ma sei preoccupato dai costi e dalle tempistiche di smantellamento delle vecchie piastrelle?<br \/>\nSPC wall panels \u00e8 la soluzione che fa per te! Rinnova il tuo bagno senza rimuovere le tue vecchie piastrelle.<\/div>\n<figure>\n\t<img decoding=\"async\" src=\"\/wp-content\/uploads\/2026\/06\/229420b2a1272352de02ecd9dafbc60be8e6150d.jpg\" alt=\"\"><figcaption><\/figcaption><\/figure>\n<figure>\n\t<img decoding=\"async\" src=\"\/wp-content\/uploads\/2026\/06\/4105af588d4ad9a6329558c3b93d03b29b3f5621.jpg\" alt=\"\"><figcaption><\/figcaption><\/figure>\n<ul>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2026\/06\/botticino-f-2.jpg\" alt=\"\"><\/p>\n<h3>Botticino<\/h3>\n<p>0010<\/p>\n<p><a href=\"\/wp-content\/uploads\/2026\/06\/botticino.jpg\"><\/a><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2026\/06\/cemento-f.jpg\" alt=\"\"><\/p>\n<h3>Cemento<\/h3>\n<p>0020<\/p>\n<p><a href=\"\/wp-content\/uploads\/2026\/06\/cemento.jpg\"><\/a><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2026\/06\/moonlight-f.jpg\" alt=\"\"><\/p>\n<h3>Moonlight<\/h3>\n<p>0030<\/p>\n<p><a href=\"\/wp-content\/uploads\/2026\/06\/moonlight.jpg\"><\/a><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2026\/06\/desert-beige-f.jpg\" alt=\"\"><\/p>\n<h3>Desert Beige<\/h3>\n<p>0040<\/p>\n<p><a href=\"\/wp-content\/uploads\/2026\/06\/deserto-beige.jpg\"><\/a><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2026\/06\/carrara-white-f.jpg\" alt=\"\"><\/p>\n<h3>Carrara White<\/h3>\n<p>0050<\/p>\n<p><a href=\"\/wp-content\/uploads\/2026\/06\/carrara-white.jpg\"><\/a><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2026\/06\/onice-grey-f.jpg\" alt=\"\"><\/p>\n<h3>Onice Grey<\/h3>\n<p>0060<\/p>\n<p><a href=\"\/wp-content\/uploads\/2026\/06\/onice-grey.jpg\"><\/a><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2026\/06\/notte-f.jpg\" alt=\"\"><\/p>\n<h3>Notte<\/h3>\n<p>0070<\/p>\n<p><a href=\"\/wp-content\/uploads\/2026\/06\/notte.jpg\"><\/a><\/p>\n<\/li>\n<\/ul>\n<hr>\n<div>\n<p><strong>Dimensione piastrella:<span class=\"oypena\">\u00a03,5x470x940mm <\/span>0,55\/33\/42\/AC5<\/strong><span class=\"oypena\"><span><o:p><\/o:p><\/span><\/span><\/p>\n<\/div>\n<p><p>\n        <a href=\"\/wp-content\/uploads\/2026\/06\/car_tec_CERAMIN.pdf\">Scheda Tecnica<\/a>\n    <\/p>\n<\/p>\n<div>\n<h3><span class=\"s1\"><b>Tecnologia Senza PVC<\/b><\/span><\/h3>\n<p class=\"p2\">A differenza dei tradizionali rivestimenti vinilici, CERAMIN \u00e8 realizzato senza PVC, plastificanti n\u00e9 sostanze nocive, contribuendo a creare ambienti pi\u00f9 salubri e confortevoli. La particolare composizione minerale assicura elevate prestazioni tecniche, una straordinaria stabilit\u00e0 dimensionale e un ridotto impatto ambientale, rappresentando una scelta responsabile per chi presta attenzione sia al design sia alla sostenibilit\u00e0.\u00a0<\/p>\n<h3><span class=\"s1\"><b>Bellezza Naturale, Prestazioni Superiori<\/b><\/span><\/h3>\n<p class=\"p2\">Le superfici CERAMIN riproducono fedelmente il fascino della pietra naturale, con texture realistiche, venature autentiche e finiture opache di grande eleganza. Ogni collezione \u00e8 progettata per integrarsi perfettamente in ambienti moderni, classici, minimalisti o industriali, offrendo infinite possibilit\u00e0 progettuali.<\/p>\n<p class=\"p2\">L\u2019elevata resistenza ai graffi, alle macchie, all\u2019usura e ai raggi UV consente di preservare inalterata la bellezza del pavimento anche dopo anni di utilizzo quotidiano.<\/p>\n<h3><span class=\"s1\"><b>Impermeabili e Adatti a Ogni Ambiente<\/b><\/span><\/h3>\n<p class=\"p2\">Grazie alla loro struttura completamente impermeabile, i rivestimenti CERAMIN sono ideali anche per cucine, bagni, lavanderie e per tutti gli ambienti soggetti all&#8217;umidit\u00e0. La loro eccezionale stabilit\u00e0 li rende inoltre perfetti per installazioni in spazi con importanti variazioni di temperatura, garantendo sempre prestazioni elevate.<\/p>\n<h3><span class=\"s1\"><b>Installazione Rapida e Manutenzione Ridotta<\/b><\/span><\/h3>\n<p class=\"p2\">Il pratico sistema ad incastro consente una posa semplice, veloce e pulita, senza necessit\u00e0 di interventi complessi. Una volta installato, il pavimento richiede soltanto una pulizia ordinaria, senza cere, trattamenti protettivi o manutenzione straordinaria.<\/p>\n<h3><span class=\"s1\"><b>Perch\u00e9 scegliere CERAMIN by Arkrea?<\/b><\/span><\/h3>\n<p class=\"p2\">\u2022 Materiale innovativo privo di PVC<br \/>\u2022 Impermeabile e resistente all\u2019umidit\u00e0<br \/>\u2022 Elevata resistenza a graffi, usura e macchie<br \/>\u2022 Aspetto autentico della pietra naturale<br \/>\u2022 Stabilit\u00e0 dimensionale superiore<br \/>\u2022 Adatto al riscaldamento a pavimento<br \/>\u2022 Facile da installare e semplice da mantenere<br \/>\u2022 Soluzione sostenibile e completamente riciclabile<\/p>\n<\/div>\n<hr>\n<p><iframe src=\"https:\/\/vimeo.com\/1205911879?share=copy&#038;fl=sv&#038;fe=ci\"><\/iframe><br \/>\n<iframe src=\"https:\/\/vimeo.com\/1205911881?share=copy&#038;fl=sv&#038;fe=ci\"><\/iframe><br \/>\n<iframe src=\"https:\/\/vimeo.com\/1205911880?share=copy&#038;fl=sv&#038;fe=ci\"><\/iframe><\/p>\n<div>\n<p>Con <strong>CERAMIN by Arkrea<\/strong> il\u00a0<span style=\"caret-color: #000000; color: #000000; font-family: -webkit-standard; font-size: medium;\">rivestimento<\/span>\u00a0diventa molto pi\u00f9 di una semplice superficie. \u00c8 una scelta di design, innovazione e responsabilit\u00e0, pensata per offrire ambienti eleganti, durevoli e in perfetta sintonia con le esigenze dell\u2019abitare contemporaneo.<\/p>\n<\/div>\n<p><!--more--><br \/>\n<!-- {\"type\":\"layout\",\"children\":[{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"padding_bottom\":\"small\",\"padding_top\":\"small\",\"style\":\"secondary\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"middle\",\"width\":\"xlarge\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"middle\",\"width_medium\":\"2-5\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"CERAMIN\",\"image_align\":\"left\",\"image_margin\":\"xsmall\",\"title_decoration\":\"divider\",\"title_element\":\"h1\",\"title_style\":\"heading-medium\"}},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Rivestimenti da parete CERAMIN: Innovazione Sostenibile per gli Interni di Domani<\/p>\n\n\",\"margin_bottom\":\"default\",\"margin_top\":\"default\",\"text_style\":\"large\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"middle\",\"width_medium\":\"3-5\"},\"children\":[{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>La collezione <strong>CERAMIN<\/strong> by Arkrea rappresenta una nuova generazione di rivestimenti da parete progettati per chi desidera coniugare design, prestazioni e rispetto per l\u2019ambiente. Grazie a un innovativo materiale minerale privo di PVC, <strong>CERAMIN<\/strong> offre una soluzione moderna e sostenibile che unisce l\u2019estetica delle superfici naturali alla praticit\u00e0 delle pi\u00f9 avanzate tecnologie per rivestimenti.<\/p>\n\n\\n\n\n<p>Ideali per abitazioni, uffici, negozi e spazi commerciali, i rivestimenti\u00a0<strong>CERAMIN<\/strong> garantiscono un perfetto equilibrio tra eleganza, durata e benessere abitativo.<\/p>\n\n\",\"margin_bottom\":\"default\",\"margin_top\":\"default\"}}]}],\"props\":{\"layout\":\"2-5,3-5\"}}]},{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"padding_bottom\":\"xsmall\",\"padding_top\":\"xsmall\",\"style\":\"primary\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"middle\",\"width\":\"xlarge\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"middle\",\"width_medium\":\"2-5\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"RINNOVA IL TUO BAGNO CON FACILITA'\",\"image_align\":\"left\",\"image_margin\":\"xsmall\",\"title_element\":\"h1\",\"title_style\":\"h2\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"3-5\"},\"children\":[{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"Vuoi ridare nuova vita ai bagni della tua casa ma sei preoccupato dai costi e dalle tempistiche di smantellamento delle vecchie piastrelle?\\nSPC wall panels \u00e8 la soluzione che fa per te! Rinnova il tuo bagno senza rimuovere le tue vecchie piastrelle.\",\"margin_bottom\":\"default\",\"margin_top\":\"default\"}}]}],\"props\":{\"layout\":\"2-5,3-5\"}}]},{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"padding_bottom\":\"small\",\"padding_top\":\"xsmall\",\"style\":\"muted\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"middle\",\"width\":\"xlarge\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"hd-image-comparison\",\"props\":{\"icon\":\"code\",\"icon_width\":\"30\",\"image_after\":\"wp-content\/uploads\/2026\/06\/4105af588d4ad9a6329558c3b93d03b29b3f5621.jpg\",\"image_after_label\":\"After\",\"image_before\":\"wp-content\/uploads\/2026\/06\/229420b2a1272352de02ecd9dafbc60be8e6150d.jpg\",\"image_before_label\":\"Before\",\"margin\":\"default\",\"show_image_labels\":true,\"slider_aria_label\":\"Percentage of before image that is visible\",\"slider_background\":\"default\",\"slider_margin_remove\":true,\"slider_start\":50,\"text_align\":\"center\"}}]}]}]},{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"middle\",\"width\":\"xlarge\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"gallery\",\"props\":{\"content_margin\":\"xsmall\",\"css\":\".el-element {\\ntext-shadow: 1px 1px #000, 1px 1px #56433D;\\n}\\n\",\"filter_align\":\"left\",\"filter_all\":true,\"filter_grid_breakpoint\":\"m\",\"filter_grid_width\":\"auto\",\"filter_position\":\"top\",\"filter_style\":\"tab\",\"grid_column_gap\":\"small\",\"grid_default\":\"1\",\"grid_medium\":\"3\",\"grid_row_gap\":\"small\",\"image_expand\":true,\"item_animation\":true,\"lightbox\":true,\"lightbox_bg_close\":true,\"link_style\":\"default\",\"link_text\":\"\",\"margin_bottom\":\"xsmall\",\"margin_top\":\"xsmall\",\"meta_align\":\"below-title\",\"meta_color\":\"primary\",\"meta_element\":\"div\",\"meta_margin\":\"xsmall\",\"meta_margin_auto\":false,\"meta_style\":\"\",\"overlay_hover\":false,\"overlay_link\":true,\"overlay_margin\":\"small\",\"overlay_mode\":\"caption\",\"overlay_padding\":\"small\",\"overlay_position\":\"bottom\",\"overlay_style\":\"\",\"overlay_transition\":\"fade\",\"show_content\":true,\"show_hover_image\":true,\"show_hover_video\":true,\"show_link\":true,\"show_meta\":true,\"show_title\":true,\"text_align\":\"center\",\"text_color\":\"light\",\"title_element\":\"h3\",\"title_hover_style\":\"reset\",\"title_margin_auto\":false,\"title_style\":\"h4\"},\"children\":[{\"type\":\"gallery_item\",\"props\":{\"image\":\"wp-content\/uploads\/2026\/06\/botticino-f-2.jpg\",\"link\":\"wp-content\/uploads\/2026\/06\/botticino.jpg\",\"meta\":\"0010\",\"title\":\"Botticino\"}},{\"type\":\"gallery_item\",\"props\":{\"image\":\"wp-content\/uploads\/2026\/06\/cemento-f.jpg\",\"link\":\"wp-content\/uploads\/2026\/06\/cemento.jpg\",\"meta\":\"0020\",\"title\":\"Cemento\"}},{\"type\":\"gallery_item\",\"props\":{\"image\":\"wp-content\/uploads\/2026\/06\/moonlight-f.jpg\",\"link\":\"wp-content\/uploads\/2026\/06\/moonlight.jpg\",\"meta\":\"0030\",\"title\":\"Moonlight\"}},{\"type\":\"gallery_item\",\"props\":{\"image\":\"wp-content\/uploads\/2026\/06\/desert-beige-f.jpg\",\"link\":\"wp-content\/uploads\/2026\/06\/deserto-beige.jpg\",\"meta\":\"0040\",\"title\":\"Desert Beige\"}},{\"type\":\"gallery_item\",\"props\":{\"image\":\"wp-content\/uploads\/2026\/06\/carrara-white-f.jpg\",\"link\":\"wp-content\/uploads\/2026\/06\/carrara-white.jpg\",\"meta\":\"0050\",\"title\":\"Carrara White\"}},{\"type\":\"gallery_item\",\"props\":{\"image\":\"wp-content\/uploads\/2026\/06\/onice-grey-f.jpg\",\"link\":\"wp-content\/uploads\/2026\/06\/onice-grey.jpg\",\"meta\":\"0060\",\"title\":\"Onice Grey\"}},{\"type\":\"gallery_item\",\"props\":{\"image\":\"wp-content\/uploads\/2026\/06\/notte-f.jpg\",\"link\":\"wp-content\/uploads\/2026\/06\/notte.jpg\",\"meta\":\"0070\",\"title\":\"Notte\"}}]},{\"type\":\"divider\",\"props\":{\"divider_element\":\"hr\"}},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p><strong>Dimensione piastrella:<span class=\\\"oypena\\\">\u00a03,5x470x940mm <\/span>0,55\/33\/42\/AC5<\/strong><span class=\\\"oypena\\\"><span><o:p><\/o:p><\/span><\/span><\/p>\n\n\",\"margin_bottom\":\"default\",\"margin_top\":\"default\",\"text_align\":\"center\",\"text_style\":\"large\"}},{\"type\":\"button\",\"props\":{\"fullwidth\":true,\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin_bottom\":\"default\",\"margin_top\":\"default\",\"text_align\":\"center\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"primary\",\"content\":\"Scheda Tecnica\",\"dialog_layout\":\"modal\",\"dialog_offcanvas_flip\":true,\"icon\":\"file-edit\",\"icon_align\":\"left\",\"link\":\"wp-content\/uploads\/2026\/06\/car_tec_CERAMIN.pdf\",\"link_target\":true}}]}]}]}]},{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"style\":\"muted\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"middle\",\"width\":\"xlarge\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<h3><span class=\\\"s1\\\"><b>Tecnologia Senza PVC<\/b><\/span><\/h3>\n\n\\n\n\n<p class=\\\"p2\\\">A differenza dei tradizionali rivestimenti vinilici, CERAMIN \u00e8 realizzato senza PVC, plastificanti n\u00e9 sostanze nocive, contribuendo a creare ambienti pi\u00f9 salubri e confortevoli. La particolare composizione minerale assicura elevate prestazioni tecniche, una straordinaria stabilit\u00e0 dimensionale e un ridotto impatto ambientale, rappresentando una scelta responsabile per chi presta attenzione sia al design sia alla sostenibilit\u00e0.\u00a0<\/p>\n\n\\n\n\n<h3><span class=\\\"s1\\\"><b>Bellezza Naturale, Prestazioni Superiori<\/b><\/span><\/h3>\n\n\\n\n\n<p class=\\\"p2\\\">Le superfici CERAMIN riproducono fedelmente il fascino della pietra naturale, con texture realistiche, venature autentiche e finiture opache di grande eleganza. Ogni collezione \u00e8 progettata per integrarsi perfettamente in ambienti moderni, classici, minimalisti o industriali, offrendo infinite possibilit\u00e0 progettuali.<\/p>\n\n\\n\n\n<p class=\\\"p2\\\">L\u2019elevata resistenza ai graffi, alle macchie, all\u2019usura e ai raggi UV consente di preservare inalterata la bellezza del pavimento anche dopo anni di utilizzo quotidiano.<\/p>\n\n\\n\n\n<h3><span class=\\\"s1\\\"><b>Impermeabili e Adatti a Ogni Ambiente<\/b><\/span><\/h3>\n\n\\n\n\n<p class=\\\"p2\\\">Grazie alla loro struttura completamente impermeabile, i rivestimenti CERAMIN sono ideali anche per cucine, bagni, lavanderie e per tutti gli ambienti soggetti all'umidit\u00e0. La loro eccezionale stabilit\u00e0 li rende inoltre perfetti per installazioni in spazi con importanti variazioni di temperatura, garantendo sempre prestazioni elevate.<\/p>\n\n\\n\n\n<h3><span class=\\\"s1\\\"><b>Installazione Rapida e Manutenzione Ridotta<\/b><\/span><\/h3>\n\n\\n\n\n<p class=\\\"p2\\\">Il pratico sistema ad incastro consente una posa semplice, veloce e pulita, senza necessit\u00e0 di interventi complessi. Una volta installato, il pavimento richiede soltanto una pulizia ordinaria, senza cere, trattamenti protettivi o manutenzione straordinaria.<\/p>\n\n\\n\n\n<h3><span class=\\\"s1\\\"><b>Perch\u00e9 scegliere CERAMIN by Arkrea?<\/b><\/span><\/h3>\n\n\\n\n\n<p class=\\\"p2\\\">\u2022 Materiale innovativo privo di PVC<br \/>\u2022 Impermeabile e resistente all\u2019umidit\u00e0<br \/>\u2022 Elevata resistenza a graffi, usura e macchie<br \/>\u2022 Aspetto autentico della pietra naturale<br \/>\u2022 Stabilit\u00e0 dimensionale superiore<br \/>\u2022 Adatto al riscaldamento a pavimento<br \/>\u2022 Facile da installare e semplice da mantenere<br \/>\u2022 Soluzione sostenibile e completamente riciclabile<\/p>\n\n\",\"margin_bottom\":\"default\",\"margin_top\":\"default\"}}]}]},{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"divider\",\"props\":{\"divider_element\":\"hr\"}}]}]},{\"type\":\"row\",\"props\":{\"layout\":\"1-3,1-3,1-3\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-3\"},\"children\":[{\"type\":\"video\",\"props\":{\"margin_bottom\":\"default\",\"margin_top\":\"default\",\"video\":\"https:\/\/vimeo.com\/1205911879?share=copy&fl=sv&fe=ci\",\"video_controls\":true,\"video_loading\":\"lazy\",\"video_width\":1920}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-3\"},\"children\":[{\"type\":\"video\",\"props\":{\"margin_bottom\":\"default\",\"margin_top\":\"default\",\"video\":\"https:\/\/vimeo.com\/1205911881?share=copy&fl=sv&fe=ci\",\"video_controls\":true,\"video_loading\":\"lazy\",\"video_width\":1920}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-3\"},\"children\":[{\"type\":\"video\",\"props\":{\"margin_bottom\":\"default\",\"margin_top\":\"default\",\"video\":\"https:\/\/vimeo.com\/1205911880?share=copy&fl=sv&fe=ci\",\"video_controls\":true,\"video_loading\":\"lazy\",\"video_width\":1920}}]}]}]},{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"middle\",\"width\":\"xlarge\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"text\",\"props\":{\"block_align\":\"center\",\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Con <strong>CERAMIN by Arkrea<\/strong> il\u00a0<span style=\\\"caret-color: #000000; color: #000000; font-family: -webkit-standard; font-size: medium;\\\">rivestimento<\/span>\u00a0diventa molto pi\u00f9 di una semplice superficie. \u00c8 una scelta di design, innovazione e responsabilit\u00e0, pensata per offrire ambienti eleganti, durevoli e in perfetta sintonia con le esigenze dell\u2019abitare contemporaneo.<\/p>\n\n\",\"margin_bottom\":\"default\",\"margin_top\":\"default\",\"maxwidth\":\"2xlarge\",\"text_align\":\"center\",\"text_style\":\"large\"}}]}]}]}],\"version\":\"5.0.36\"} --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CERAMIN Rivestimenti da parete CERAMIN: Innovazione Sostenibile per gli Interni di Domani La collezione CERAMIN by Arkrea rappresenta una nuova generazione di rivestimenti da parete progettati per chi desidera coniugare design, prestazioni e rispetto per l\u2019ambiente. Grazie a un innovativo materiale minerale privo di PVC, CERAMIN offre una soluzione moderna e sostenibile che unisce l\u2019estetica [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-385","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/arkrea.net\/fr\/wp-json\/wp\/v2\/pages\/385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arkrea.net\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/arkrea.net\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/arkrea.net\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/arkrea.net\/fr\/wp-json\/wp\/v2\/comments?post=385"}],"version-history":[{"count":12,"href":"https:\/\/arkrea.net\/fr\/wp-json\/wp\/v2\/pages\/385\/revisions"}],"predecessor-version":[{"id":484,"href":"https:\/\/arkrea.net\/fr\/wp-json\/wp\/v2\/pages\/385\/revisions\/484"}],"wp:attachment":[{"href":"https:\/\/arkrea.net\/fr\/wp-json\/wp\/v2\/media?parent=385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}